{"id":18008023,"date":"2025-12-01T08:19:02","date_gmt":"2025-12-01T07:19:02","guid":{"rendered":"https:\/\/kapitalis.com\/tunisie\/?p=18008023"},"modified":"2025-12-01T08:19:04","modified_gmt":"2025-12-01T07:19:04","slug":"tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025","status":"publish","type":"post","link":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/","title":{"rendered":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025"},"content":{"rendered":"\n<p><strong><em>La <a href=\"https:\/\/tickets.roadtoqatar.qa\/fifa-arab-cup\/\">Coupe arabe de la Fifa 2025<\/a><\/em><\/strong><strong><em>, la plus grande comp\u00e9tition de football du monde arabe, d\u00e9butera ce lundi 1<sup>er<\/sup> d\u00e9cembre 20225 avec le match d\u2019ouverture opposant l\u2019\u00e9quipe de Tunisie, diminu\u00e9e d\u2019une dizaine de joueurs, \u00e0 celle de la Syrie, \u00e0 14h00, heure tunisienne. Cet article est une pr\u00e9sentation g\u00e9n\u00e9rale de cette comp\u00e9tition, qui a lieu tous les quatre ans. Au total, 16 \u00e9quipes de toute la r\u00e9gion s&rsquo;affronteront pour le titre et d\u2019ici la fin de ce tournoi, le 18 d\u00e9cembre, le public verra 32 matchs.<\/em><\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Quand et o\u00f9&nbsp;?<\/h2>\n\n\n\n<p>La phase de groupes&nbsp;aura lieu du 1<sup>er<\/sup> au 9 d\u00e9cembre, les quarts de finale&nbsp;les 11 et 12 d\u00e9cembre, les demi-finales&nbsp;le 15 d\u00e9cembre, le match pour la troisi\u00e8me place&nbsp;le 18 d\u00e9cembre et la finale&nbsp;le 18 d\u00e9cembre.<\/p>\n\n\n\n<p>Le Qatar organise la Coupe arabe pour la troisi\u00e8me fois, apr\u00e8s les \u00e9ditions de 1998 et 2021. C\u2019est \u00e9galement le deuxi\u00e8me tournoi Fifa cons\u00e9cutif organis\u00e9 par ce pays du Golfe, apr\u00e8s la r\u00e9cente Coupe du Monde U-17 de la Fifa.<\/p>\n\n\n\n<p>Six sites ont \u00e9t\u00e9 choisis pour accueillir cette comp\u00e9tition r\u00e9gionale, chacun ayant d\u00e9j\u00e0 accueilli une Coupe du Monde de la Fifa il y a trois ans.<\/p>\n\n\n\n<p>Comme lors de Qatar 2022, le stade Al Bayt, situ\u00e9 dans la ville d\u2019Al Khor, au nord du pays, accueillera le match d\u2019ouverture, tandis que le magnifique stade de Lusail sera le th\u00e9\u00e2tre de la finale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les villes h\u00f4tes et leurs stades\u00a0:<\/h2>\n\n\n\n<p>Lusail&nbsp;: Stade de Lusail (capacit\u00e9&nbsp;: 88&nbsp;966 places);<\/p>\n\n\n\n<p>Al Rayyan&nbsp;: Stade Ahmad bin Ali (capacit\u00e9&nbsp;: 45&nbsp;032 places);<\/p>\n\n\n\n<p>Al Khor&nbsp;: Stade Al Bayt (capacit\u00e9&nbsp;: 68&nbsp;895 places);<\/p>\n\n\n\n<p>Doha&nbsp;: Stade 974 (capacit\u00e9&nbsp;: 44&nbsp;089 places); Stade de la Cit\u00e9 de l\u2019\u00c9ducation (capacit\u00e9&nbsp;: 44&nbsp;667 places); Stade international Khalifa (capacit\u00e9&nbsp;: 45&nbsp;857 places).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les nations participantes\u00a0:<\/h2>\n\n\n\n<p>Seize nations, issues de la Conf\u00e9d\u00e9ration asiatique de football (AFC) et de la Conf\u00e9d\u00e9ration africaine de football (CAF), disputeront le tournoi.<\/p>\n\n\n\n<p>Le Qatar, pays h\u00f4te, et l\u2019Alg\u00e9rie, tenante du titre, ainsi que les sept nations les mieux class\u00e9es au moment du tirage au sort en mai, se sont qualifi\u00e9s d\u2019office.<\/p>\n\n\n\n<p>Les sept places restantes ont \u00e9t\u00e9 attribu\u00e9es lors de matchs de qualification \u00e0 \u00e9limination directe.<\/p>\n\n\n\n<p>Les nations participantes ont \u00e9t\u00e9 r\u00e9parties en quatre groupes :<\/p>\n\n\n\n<p><strong><em>Groupe A :<\/em><\/strong> Tunisie, Syrie, Qatar, Palestine&nbsp;;<\/p>\n\n\n\n<p><strong><em>Groupe B :<\/em><\/strong> Maroc, Comores, Arabie saoudite, Oman&nbsp;;<\/p>\n\n\n\n<p><strong><em>Groupe C :<\/em><\/strong> \u00c9gypte, Kowe\u00eft, Jordanie, \u00c9mirats arabes unis;<\/p>\n\n\n\n<p><strong><em>Groupe D :<\/em><\/strong><strong> <\/strong>Alg\u00e9rie, Soudan, Irak, Bahre\u00efn.<\/p>\n\n\n\n<p>Les deux meilleures \u00e9quipes de chaque groupe se qualifient pour la phase \u00e0 \u00e9limination directe, qui comprend les quarts de finale, les demi-finales et la finale. Un match pour la troisi\u00e8me place opposera \u00e9galement les deux \u00e9quipes perdantes des demi-finales.<\/p>\n\n\n\n<p>En phase \u00e0 \u00e9limination directe, si un match est \u00e0 \u00e9galit\u00e9 \u00e0 la fin du temps r\u00e9glementaire, une prolongation de 30 minutes est jou\u00e9e, suivie, si n\u00e9cessaire, d\u2019une s\u00e9ance de tirs au but.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Montant des prix&nbsp;:<\/h2>\n\n\n\n<p>L\u2019\u00e9dition 2025 offrira une dotation record de plus de 36,5 millions de dollars, rejoignant ainsi le cercle tr\u00e8s ferm\u00e9 des plus grands tournois internationaux de football.<\/p>\n\n\n\n<p>La derni\u00e8re \u00e9dition, en 2021, proposait une dotation de 25,5 millions de dollars.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les pr\u00e9c\u00e9dents vainqueurs&nbsp;:<\/h2>\n\n\n\n<p>L\u2019Irak est l\u2019\u00e9quipe la plus titr\u00e9e de la Coupe arabe avec quatre titres. L\u2019Arabie saoudite arrive en deuxi\u00e8me position avec deux titres, tandis que la Tunisie, l\u2019\u00c9gypte, le Maroc et l\u2019Alg\u00e9rie comptent chacun un titre.<\/p>\n\n\n\n<p>L&rsquo;Alg\u00e9rie est la championne en titre, apr\u00e8s avoir battu la Tunisie 2-0 en prolongation lors de la finale de 2021.<\/p>\n\n\n\n<p>Historiquement, les nations asiatiques ont remport\u00e9 plus de titres (6) que celles d\u2019Afrique (4). R\u00e9unissant certaines des meilleures \u00e9quipes du monde, la Coupe arabe donnera aux supporters un avant-go\u00fbt du niveau des nations arabes lors de la prochaine Coupe du Monde de la Fifa.<\/p>\n\n\n\n<p>Sept participants \u00e0 la Coupe arabe \u2013 le Qatar, la Tunisie, le Maroc, l\u2019Arabie saoudite, l\u2019\u00c9gypte, la Jordanie et l\u2019Alg\u00e9rie \u2013 participeront \u00e9galement \u00e0 la Coupe du Monde de la Fifa 2026, co-organis\u00e9e par les \u00c9tats-Unis, le Mexique et le Canada.<\/p>\n\n\n\n<p>Avec une Coupe du Monde remani\u00e9e qui accueillera 48 \u00e9quipes, la Coupe arabe pourrait servir de tremplin aux \u00e9quipes ambitionnant d\u2019aller loin sur la plus grande sc\u00e8ne du football. Les \u00e9quipes favorites :<\/p>\n\n\n\n<p>&nbsp;Au vu de leurs r\u00e9centes performances lors des qualifications pour la Coupe du Monde 2026, pas moins de cinq \u00e9quipes pourraient pr\u00e9tendre au titre. Parmi elles, la Tunisie, qui a engrang\u00e9 le plus de points (28 sur 30 possibles) parmi toutes les nations de la CAF durant les \u00e9liminatoires, remportant neuf de ses dix matchs et terminant premi\u00e8re de son groupe.<\/p>\n\n\n\n<p>L&rsquo;Alg\u00e9rie et le Maroc, voisins nord-africains, font partie des favoris apr\u00e8s s\u2019\u00eatre qualifi\u00e9s pour la Coupe du Monde en terminant premiers de leur groupe. L\u2019\u00c9gypte, sept fois championne d\u2019Afrique, est \u00e9galement parmi les pr\u00e9tendants au titre.<\/p>\n\n\n\n<p>La Jordanie, qualifi\u00e9e pour la premi\u00e8re fois, est consid\u00e9r\u00e9e comme outsider.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les joueurs \u00e0 suivre&nbsp;:<\/h2>\n\n\n\n<p>Le Jordanien Ali Olwan, troisi\u00e8me meilleur buteur des qualifications de l\u2019AFC pour la Coupe du Monde avec neuf buts, sera un joueur \u00e0 surveiller de pr\u00e8s durant le tournoi. L\u2019Irakien Aymen Hussein, quatri\u00e8me meilleur buteur avec huit r\u00e9alisations, figure \u00e9galement parmi les attaquants susceptibles de repr\u00e9senter une menace s\u00e9rieuse.<\/p>\n\n\n\n<p>Les supporters devront aussi garder un \u0153il sur le solide gardien tunisien Aymen Dahmen, auteur de six clean sheets et d\u2019une s\u00e9rie de dix matchs sans encaisser de but en qualifications.<\/p>\n\n\n\n<p>L\u2019attaquant Akram Afif, dont le nom est devenu synonyme du succ\u00e8s du Qatar ces dix derni\u00e8res ann\u00e9es, est un joueur cl\u00e9 pour le pays h\u00f4te. Quant au capitaine saoudien Salem Al-Dawsari, il est en bonne forme ces derniers temps et occupe la quatri\u00e8me place du classement des passeurs d\u00e9cisifs de la Saudi Pro League.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les billets :<\/h2>\n\n\n\n<p>Les billets pour la Coupe arabe de la Fifa ont \u00e9t\u00e9 mis en vente sur la <a href=\"https:\/\/tickets.roadtoqatar.qa\/fifa-arab-cup\/\" target=\"_blank\" rel=\"noreferrer noopener\">plateforme officielle<\/a> fin septembre. Les supporters pouvaient acheter des billets pour chaque match, r\u00e9partis en trois cat\u00e9gories de prix, \u00e0 partir de 7\u00a0dollars US.<\/p>\n\n\n\n<p>Le tournoi proposait \u00e9galement des packs par \u00e9quipe, incluant trois matchs de poule par nation, \u00e0 partir d\u2019environ 20&nbsp;dollars US. Ces packs ne sont plus disponibles.<\/p>\n\n\n\n<p>Les billets pour la finale, \u00e0 partir de 14&nbsp;dollars US, sont \u00e9puis\u00e9s.<\/p>\n\n\n\n<p>Au Moyen-Orient et en Afrique du Nord, vous pouvez suivre l\u2019int\u00e9gralit\u00e9 du tournoi du 1<sup>er<\/sup> au 18&nbsp;d\u00e9cembre, exclusivement en arabe et uniquement sur beIN Sports PPV.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00. <\/p>\n","protected":false},"author":8,"featured_media":18008146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[992,999,2433],"tags":[54492,26883,125879,390,756,62643],"class_list":["post-18008023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-sport","category-tunisie","tag-aymen-dahmen","tag-bein-sports","tag-coupe-arabe-de-la-fifa-2025","tag-football","tag-qatar","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis<\/title>\n<meta name=\"description\" content=\"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis\" \/>\n<meta property=\"og:description\" content=\"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Kapitalis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KapitalisInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T07:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T07:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster kapitalis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:site\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster kapitalis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\"},\"author\":{\"name\":\"webmaster kapitalis\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\"},\"headline\":\"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025\",\"datePublished\":\"2025-12-01T07:19:02+00:00\",\"dateModified\":\"2025-12-01T07:19:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\"},\"wordCount\":1143,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg\",\"keywords\":[\"Aymen Dahmen\",\"BeIN Sports\",\"Coupe arabe de la Fifa 2025\",\"Football\",\"Qatar\",\"Tunisie\"],\"articleSection\":[\"A LA UNE\",\"SPORT\",\"Tunisie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\",\"name\":\"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg\",\"datePublished\":\"2025-12-01T07:19:02+00:00\",\"dateModified\":\"2025-12-01T07:19:04+00:00\",\"description\":\"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.\",\"breadcrumb\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg\",\"contentUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/kapitalis.com\/tunisie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"name\":\"Kapitalis\",\"description\":\"L&#039;actualit\u00e9 en Tunisie et dans le monde\",\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\",\"name\":\"Kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"contentUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"width\":5000,\"height\":1500,\"caption\":\"Kapitalis\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KapitalisInfo\/\",\"https:\/\/x.com\/KapitalisInfo\",\"https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\",\"name\":\"webmaster kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis","description":"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis","og_description":"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.","og_url":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/","og_site_name":"Kapitalis","article_publisher":"https:\/\/www.facebook.com\/KapitalisInfo\/","article_published_time":"2025-12-01T07:19:02+00:00","article_modified_time":"2025-12-01T07:19:04+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg","type":"image\/jpeg"}],"author":"webmaster kapitalis","twitter_card":"summary_large_image","twitter_creator":"@KapitalisInfo","twitter_site":"@KapitalisInfo","twitter_misc":{"\u00c9crit par":"webmaster kapitalis","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#article","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/"},"author":{"name":"webmaster kapitalis","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9"},"headline":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025","datePublished":"2025-12-01T07:19:02+00:00","dateModified":"2025-12-01T07:19:04+00:00","mainEntityOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/"},"wordCount":1143,"commentCount":1,"publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg","keywords":["Aymen Dahmen","BeIN Sports","Coupe arabe de la Fifa 2025","Football","Qatar","Tunisie"],"articleSection":["A LA UNE","SPORT","Tunisie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/","url":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/","name":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025 - Kapitalis","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg","datePublished":"2025-12-01T07:19:02+00:00","dateModified":"2025-12-01T07:19:04+00:00","description":"La Coupe arabe de la Fifa 2025 d\u00e9butera ce lundi 1er d\u00e9cembre 20225 avec le match d\u2019ouverture opposant la Tunisie \u00e0 la Syrie, \u00e0 14h00.","breadcrumb":{"@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#primaryimage","url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg","contentUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2025\/12\/Fifa-Arab-Cup-2025.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/kapitalis.com\/tunisie\/2025\/12\/01\/tout-ce-quil-faut-savoir-sur-la-coupe-arabe-de-la-fifa-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kapitalis.com\/tunisie\/"},{"@type":"ListItem","position":2,"name":"Tout ce qu\u2019il faut savoir sur la Coupe arabe de la Fifa 2025"}]},{"@type":"WebSite","@id":"https:\/\/kapitalis.com\/tunisie\/#website","url":"https:\/\/kapitalis.com\/tunisie\/","name":"Kapitalis","description":"L&#039;actualit\u00e9 en Tunisie et dans le monde","publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kapitalis.com\/tunisie\/#organization","name":"Kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/","url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","contentUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","width":5000,"height":1500,"caption":"Kapitalis"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KapitalisInfo\/","https:\/\/x.com\/KapitalisInfo","https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q"]},{"@type":"Person","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9","name":"webmaster kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/"}]}},"_links":{"self":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/18008023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/comments?post=18008023"}],"version-history":[{"count":1,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/18008023\/revisions"}],"predecessor-version":[{"id":18008151,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/18008023\/revisions\/18008151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media\/18008146"}],"wp:attachment":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media?parent=18008023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/categories?post=18008023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/tags?post=18008023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}