{"id":19042771,"date":"2026-06-25T10:15:19","date_gmt":"2026-06-25T09:15:19","guid":{"rendered":"https:\/\/kapitalis.com\/tunisie\/?p=19042771"},"modified":"2026-06-25T10:15:20","modified_gmt":"2026-06-25T09:15:20","slug":"70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat","status":"publish","type":"post","link":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/","title":{"rendered":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>L\u2019arm\u00e9e nationale tunisienne c\u00e9l\u00e8bre le 70<sup>e<\/sup> anniversaire de sa cr\u00e9ation en 1956, quelques mois apr\u00e8s l\u2019ind\u00e9pendance, acquise le 20 mars 1956. Devenue l\u2019une des institutions piliers de l\u2019\u00c9tat tunisien, engag\u00e9e dans la lutte pour la pleine souverainet\u00e9 nationale ainsi que dans les d\u00e9fis de s\u00e9curit\u00e9, de d\u00e9veloppement et de coop\u00e9ration internationale, elle s\u2019est toujours gard\u00e9e, \u00e0 la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, de se m\u00ealer directement \u00e0 la politique, et c\u2019est ce qui fait sa sp\u00e9cificit\u00e9 et sa diff\u00e9rence, malgr\u00e9 les tentatives visant \u00e0 l\u2019impliquer davantage dans la gestion des conflits internes.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Latif Belhedi<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Selon l\u2019agence de presse officielle Tap, cet anniversaire rappelle le r\u00f4le des forces arm\u00e9es dans la consolidation de la souverainet\u00e9 nationale en prenant part aux \u00e9v\u00e9nements de Sakiet Sidi Youssef en f\u00e9vrier 1958, \u00e0 la bataille de Remada en mai de la m\u00eame ann\u00e9e et \u00e0 la bataille de l\u2019\u00e9vacuation de Bizerte en juillet 1961, qui s\u2019est achev\u00e9e le 15 octobre 1963 avec le d\u00e9part du dernier soldat fran\u00e7ais du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui, l\u2019arm\u00e9e tunisienne est engag\u00e9e non seulement dans la d\u00e9fense du territoire et la protection des fronti\u00e8res, mais aussi dans la lutte contre le terrorisme, la lutte contre l\u2019immigration irr\u00e9guli\u00e8re, la r\u00e9ponse aux catastrophes naturelles et le soutien logistique \u00e0 l\u2019\u00c9tat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour marquer cet anniversaire, le minist\u00e8re de la D\u00e9fense organise, du 20 au 26 juin, une exposition documentaire sur l\u2019avenue Habib Bourguiba \u00e0 Tunis, consacr\u00e9e \u00e0 l\u2019histoire, aux missions et \u00e0 l\u2019\u00e9volution de l\u2019institution militaire. L\u2019exposition met \u00e9galement en lumi\u00e8re la contribution de l\u2019arm\u00e9e \u00e0 la formation professionnelle, au d\u00e9veloppement des r\u00e9gions int\u00e9rieures et sahariennes, ainsi qu\u2019aux missions internationales de maintien de la paix.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un contexte r\u00e9gional marqu\u00e9 par l\u2019instabilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cette c\u00e9l\u00e9bration intervient dans un contexte r\u00e9gional marqu\u00e9 par l\u2019instabilit\u00e9 en Libye, les flux migratoires et les tensions en M\u00e9diterran\u00e9e et au Sahel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce contexte, le 70<sup>e<\/sup> anniversaire rev\u00eat \u00e9galement une importance politique&nbsp;: il r\u00e9affirme le r\u00f4le de l\u2019arm\u00e9e comme institution r\u00e9publicaine centrale, garante de la souverainet\u00e9 et de la stabilit\u00e9 tunisiennes. Sa mission ne se limite pas \u00e0 la protection de l\u2019int\u00e9grit\u00e9 territoriale, elle consiste aussi au soutien au d\u00e9veloppement du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cr\u00e9ation de l\u2019arm\u00e9e tunisienne s\u2019inscrivait dans le cadre du processus de consolidation de l\u2019ind\u00e9pendance. Les forces arm\u00e9es furent appel\u00e9es \u00e0 combattre les derniers bastions de la pr\u00e9sence coloniale fran\u00e7aise, notamment lors des \u00e9v\u00e9nements de Sakiet Sidi Youssef en f\u00e9vrier 1958, de la bataille de Remada en mai de la m\u00eame ann\u00e9e et de la bataille de Bizerte en juillet 1961, qui s&rsquo;ach\u00e8vera par le retrait d\u00e9finitif des troupes fran\u00e7aises le 15 octobre 1963.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui, l\u2019arm\u00e9e continue de jouer un r\u00f4le central dans la s\u00e9curit\u00e9 nationale, contribuant \u00e0 la lutte contre le terrorisme, le crime organis\u00e9, la contrebande, le trafic d\u2019\u00eatres humains et l\u2019immigration clandestine. Elle participe \u00e9galement aux op\u00e9rations de protection civile, \u00e0 la lutte contre les incendies et apporte son aide lors de situations d\u2019urgence et de catastrophes naturelles.<\/p>\n\n\n\n<figure class=\"wp-block-embed alignleft is-type-wp-embed is-provider-kapitalis wp-block-embed-kapitalis\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"MdYcoGAGQO\"><a href=\"https:\/\/kapitalis.com\/tunisie\/2023\/07\/31\/pourquoi-larmee-tunisienne-soutient-elle-kais-saied\/\">Pourquoi l\u2019arm\u00e9e tunisienne soutient-elle Ka\u00efs Sa\u00efed ? \u00a0<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Pourquoi l\u2019arm\u00e9e tunisienne soutient-elle Ka\u00efs Sa\u00efed ? \u00a0\u00a0\u00bb \u2014 Kapitalis\" src=\"https:\/\/kapitalis.com\/tunisie\/2023\/07\/31\/pourquoi-larmee-tunisienne-soutient-elle-kais-saied\/embed\/#?secret=JlsSJ4dpMM#?secret=MdYcoGAGQO\" data-secret=\"MdYcoGAGQO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">60 ans au service de la paix dans le monde<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le plan international, la Tunisie peut se targuer de plus de soixante ans de participation aux missions de maintien de la paix des Nations Unies. En 1960, le pr\u00e9sident Habib Bourguiba d\u00e9cida d\u2019envoyer 3&nbsp;000 soldats au Congo, inaugurant une collaboration avec l\u2019Onu qui a permis, \u00e0 ce jour, la participation \u00e0 26 missions internationales et le d\u00e9ploiement de contingents de soldats tunisiens. Actuellement, plus de 800 personnes sont engag\u00e9es dans la mission de l\u2019Onu en R\u00e9publique centrafricaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces derni\u00e8res ann\u00e9es, la Tunisie a investi dans la production militaire nationale afin de r\u00e9duire sa d\u00e9pendance aux importations et de ma\u00eetriser ses d\u00e9penses de d\u00e9fense. Parmi les r\u00e9alisations les plus significatives figurent le v\u00e9hicule blind\u00e9 r\u00e9sistant aux mines <em>\u00abBarb\u00bb<\/em>, con\u00e7u et construit par des techniciens militaires tunisiens, et la construction de navires de guerre de fabrication locale, dont le patrouilleur <em>\u00abIstiqlal B201\u00bb<\/em>. Un nouveau patrouilleur de 52 m\u00e8tres pour la Marine tunisienne est \u00e9galement en construction, avec une mise en service pr\u00e9vue pour fin 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette strat\u00e9gie de production militaire r\u00e9pond non seulement aux besoins de s\u00e9curit\u00e9, mais constitue \u00e9galement un moteur de croissance industrielle, d\u2019innovation technologique, de formation professionnelle et de cr\u00e9ation d\u2019emplois.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A l\u2019\u00e9cart des man\u0153uvres politiciennes pour le pouvoir<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019arm\u00e9e tunisienne a certes souvent \u00e9t\u00e9 entra\u00een\u00e9e \u00e0 g\u00e9rer des situations extr\u00eames et a fait face \u00e0 de nombreuses tentatives du pouvoir politique de l\u2019entra\u00eener dans le sillage de ses conflits internes, mais elle a toujours su r\u00e9sister, jusque-l\u00e0, \u00e0 la tentation de s\u2019y impliquer. Sous Bourguiba, comme sous Ben Ali et m\u00eame apr\u00e8s, elle s\u2019est toujours tenue \u00e0 l\u2019\u00e9cart des man\u0153uvres politiciennes pour le pouvoir. Ce fut le cas apr\u00e8s la fuite de Ben Ali le 14 janvier 2011. Ce soir-l\u00e0, lors d\u2019une r\u00e9union de crise au minist\u00e8re de l\u2019Int\u00e9rieur, le chef d\u2019\u00e9tat-major de l\u2019\u00e9poque, le g\u00e9n\u00e9ral Rachid Ammar, avait r\u00e9pondu vertement au Premier ministre Mohamed Ghannouchi qui lui demandait de prendre les commandes du pays. <em>\u00abCe sont les politiciens qui ont cr\u00e9\u00e9 cette situation. Et c\u2019est \u00e0 eux de la g\u00e9rer de la meilleure fa\u00e7on possible. Le r\u00f4le de l\u2019arm\u00e9e consiste \u00e0 prot\u00e9ger le pays et \u00e0 garder ses fronti\u00e8res\u00bb<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pouvoir \u00e9tait \u00e0 prendre, mais l\u2019arm\u00e9e s\u2019\u00e9tait gard\u00e9e de faire le pas, et cela m\u00e9rite d\u2019\u00eatre soulign\u00e9. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s r\u00e9cemment, et en r\u00e9action \u00e0 des appels politiques interpellant l\u2019arm\u00e9e tunisienne sur la situation politique int\u00e9rieure dans le pays, relay\u00e9s par certains m\u00e9dias, le minist\u00e8re de la D\u00e9fense nationale a rompu son silence habituel pour rappeler, dans un <a href=\"https:\/\/kapitalis.com\/tunisie\/2026\/05\/21\/le-ministere-de-la-defense-reaffirme-la-neutralite-de-linstitution-militaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">communiqu\u00e9 <\/a>au ton ferme, diffus\u00e9 le 21 mai 2026, les fondements r\u00e9publicains de l\u2019arm\u00e9e tunisienne : sa neutralit\u00e9, son refus d\u2019\u00eatre impliqu\u00e9e dans des <em>\u00abtiraillements politiques\u00bb<\/em> et son attachement aux lois de l\u2019\u00c9tat.<\/p>\n\n\n\n<figure class=\"wp-block-embed alignleft is-type-wp-embed is-provider-kapitalis wp-block-embed-kapitalis\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"OVfsbVj9KZ\"><a href=\"https:\/\/kapitalis.com\/tunisie\/2026\/05\/24\/tunisie-quand-un-communique-de-larmee-devient-un-test-de-verite\/\">Tunisie | Quand un communiqu\u00e9 de l\u2019arm\u00e9e devient un test de v\u00e9rit\u00e9<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Tunisie | Quand un communiqu\u00e9 de l\u2019arm\u00e9e devient un test de v\u00e9rit\u00e9\u00a0\u00bb \u2014 Kapitalis\" src=\"https:\/\/kapitalis.com\/tunisie\/2026\/05\/24\/tunisie-quand-un-communique-de-larmee-devient-un-test-de-verite\/embed\/#?secret=TZCpsRzab2#?secret=OVfsbVj9KZ\" data-secret=\"OVfsbVj9KZ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l&rsquo;arm\u00e9e tunisienne s&rsquo;est toujours gard\u00e9e de se m\u00ealer directement de politique. <\/p>\n","protected":false},"author":8,"featured_media":19042816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[992,997,2433],"tags":[4447,140,163,4171,62643],"class_list":["post-19042771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-politique","category-tunisie","tag-armee-tunisienne","tag-ben-ali","tag-bourguiba","tag-rachid-ammar","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis<\/title>\n<meta name=\"description\" content=\"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l&#039;arm\u00e9e tunisienne s&#039;est toujours gard\u00e9e de se m\u00ealer de la politique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis\" \/>\n<meta property=\"og:description\" content=\"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l&#039;arm\u00e9e tunisienne s&#039;est toujours gard\u00e9e de se m\u00ealer de la politique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\" \/>\n<meta property=\"og:site_name\" content=\"Kapitalis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KapitalisInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T09:15:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T09:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster kapitalis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:site\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster kapitalis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\"},\"author\":{\"name\":\"webmaster kapitalis\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\"},\"headline\":\"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat\",\"datePublished\":\"2026-06-25T09:15:19+00:00\",\"dateModified\":\"2026-06-25T09:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\"},\"wordCount\":1104,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg\",\"keywords\":[\"arm\u00e9e tunisienne\",\"Ben Ali\",\"Bourguiba\",\"Rachid Ammar\",\"Tunisie\"],\"articleSection\":[\"A LA UNE\",\"POLITIQUE\",\"Tunisie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\",\"name\":\"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg\",\"datePublished\":\"2026-06-25T09:15:19+00:00\",\"dateModified\":\"2026-06-25T09:15:20+00:00\",\"description\":\"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l'arm\u00e9e tunisienne s'est toujours gard\u00e9e de se m\u00ealer de la politique.\",\"breadcrumb\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg\",\"contentUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/kapitalis.com\/tunisie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"name\":\"Kapitalis\",\"description\":\"L&#039;actualit\u00e9 en Tunisie et dans le monde\",\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\",\"name\":\"Kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"contentUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"width\":5000,\"height\":1500,\"caption\":\"Kapitalis\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KapitalisInfo\/\",\"https:\/\/x.com\/KapitalisInfo\",\"https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\",\"name\":\"webmaster kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis","description":"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l'arm\u00e9e tunisienne s'est toujours gard\u00e9e de se m\u00ealer de la politique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/","og_locale":"fr_FR","og_type":"article","og_title":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis","og_description":"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l'arm\u00e9e tunisienne s'est toujours gard\u00e9e de se m\u00ealer de la politique.","og_url":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/","og_site_name":"Kapitalis","article_publisher":"https:\/\/www.facebook.com\/KapitalisInfo\/","article_published_time":"2026-06-25T09:15:19+00:00","article_modified_time":"2026-06-25T09:15:20+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg","type":"image\/jpeg"}],"author":"webmaster kapitalis","twitter_card":"summary_large_image","twitter_creator":"@KapitalisInfo","twitter_site":"@KapitalisInfo","twitter_misc":{"\u00c9crit par":"webmaster kapitalis","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#article","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/"},"author":{"name":"webmaster kapitalis","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9"},"headline":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat","datePublished":"2026-06-25T09:15:19+00:00","dateModified":"2026-06-25T09:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/"},"wordCount":1104,"commentCount":2,"publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage"},"thumbnailUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg","keywords":["arm\u00e9e tunisienne","Ben Ali","Bourguiba","Rachid Ammar","Tunisie"],"articleSection":["A LA UNE","POLITIQUE","Tunisie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/","url":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/","name":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat - Kapitalis","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage"},"thumbnailUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg","datePublished":"2026-06-25T09:15:19+00:00","dateModified":"2026-06-25T09:15:20+00:00","description":"A la diff\u00e9rence de la plupart des arm\u00e9es arabes et africaines, l'arm\u00e9e tunisienne s'est toujours gard\u00e9e de se m\u00ealer de la politique.","breadcrumb":{"@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#primaryimage","url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg","contentUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2026\/06\/Armee-tunisienne.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/kapitalis.com\/tunisie\/2026\/06\/25\/70e-anniversaire-de-larmee-tunisienne-neutralite-politique-et-loyaute-a-letat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kapitalis.com\/tunisie\/"},{"@type":"ListItem","position":2,"name":"70e anniversaire de l\u2019arm\u00e9e tunisienne | Neutralit\u00e9 politique et loyaut\u00e9 \u00e0 l\u2019Etat"}]},{"@type":"WebSite","@id":"https:\/\/kapitalis.com\/tunisie\/#website","url":"https:\/\/kapitalis.com\/tunisie\/","name":"Kapitalis","description":"L&#039;actualit\u00e9 en Tunisie et dans le monde","publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kapitalis.com\/tunisie\/#organization","name":"Kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/","url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","contentUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","width":5000,"height":1500,"caption":"Kapitalis"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KapitalisInfo\/","https:\/\/x.com\/KapitalisInfo","https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q"]},{"@type":"Person","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9","name":"webmaster kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/"}]}},"_links":{"self":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/19042771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/comments?post=19042771"}],"version-history":[{"count":1,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/19042771\/revisions"}],"predecessor-version":[{"id":19042890,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/19042771\/revisions\/19042890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media\/19042816"}],"wp:attachment":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media?parent=19042771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/categories?post=19042771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/tags?post=19042771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}