{"id":62979,"date":"2016-08-29T11:20:40","date_gmt":"2016-08-29T10:20:40","guid":{"rendered":"http:\/\/kapitalis.com\/tunisie\/?p=62979"},"modified":"2016-08-29T09:28:25","modified_gmt":"2016-08-29T08:28:25","slug":"mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa","status":"publish","type":"post","link":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/","title":{"rendered":"\u00abMesures douloureuses\u00bb &#8211; Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-62980\" src=\"http:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2016\/08\/Youssef-Chahed-Gafsa.jpg\" alt=\"Youssef-Chahed-Gafsa\" width=\"626\" height=\"380\" \/><\/p>\n<p style=\"text-align: left;\"><em><strong>Le nouveau chef du gouvernement Youssef Chahed usera-t-il de coercition pour faire red\u00e9marrer la machine de production de phosphate \u00e0 Gafsa ?<\/strong><\/em><\/p>\n<p style=\"text-align: left;\">Par <strong>Ass\u00e2ad Jom\u00e2a<\/strong> *<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\">J\u2019avais dans un pr\u00e9c\u00e9dent billet reproch\u00e9 \u00e0 nos politiciens leur manque de cr\u00e9ativit\u00e9. Leurs man\u0153uvres politiciennes \u00e9tant, \u00e0 ce point, pr\u00e9visibles que l\u2019on pourrait presque les identifier aux automatismes caract\u00e9risant ce bon vieux \u00abr\u00e9flexe de Pavlov\u00bb.<br \/>\nC\u2019est en partant de ce constat que je vais planter le d\u00e9cor de ce qu\u2019ils tiennent pour fa\u00eete de maestria politique et qui n\u2019est en r\u00e9alit\u00e9 qu\u2019une p\u00e2le copie des sc\u00e9narios v\u00e9cus d\u00e9j\u00e0 sous le r\u00e8gne de Ben Ali.<\/p>\n<p style=\"text-align: left;\"><strong>Sc\u00e8nes du tumulte ordinaire<\/strong><\/p>\n<p style=\"text-align: left;\"><em>Sc\u00e8ne I<\/em> : Tout le monde en est, aujourd\u2019hui, conscient: le parti Nidaa n\u2019a finalement \u00e9t\u00e9 qu\u2019une formidable machine \u00e9lectorale. Jouant sur les hantises des femmes, craignant l\u2019av\u00e8nement d\u2019un r\u00e9gime th\u00e9ocratique, promettant monts et merveilles \u00e0 tous les citoyens, il est parvenu, faisant illusion, \u00e0 se hisser aux commandes du pays. R\u00e9gnant, certes, mais incapable de gouverner, il s\u2019est assur\u00e9 des bons et loyaux services d\u2019un parti bien implant\u00e9 dans le pays, rigoureusement structur\u00e9 telle une colonne en marche et, par-dessus tout, aussi disciplin\u00e9 qu\u2019une arm\u00e9e spartiate, j\u2019ai nomm\u00e9 Ennahdha.<\/p>\n<p style=\"text-align: left;\">Le parti islamiste tunisien, dans un besoin pressant de se refaire une virginit\u00e9, ne s\u2019est pas fait prier pour officier en Saint Bernard \u00e0 chaque fois que le besoin s\u2019en est fait sentir. Derni\u00e8re servitude, la \u00ab<em>visite<\/em>\u00bb de son \u00e9mir \u00e0 Gafsa, Rached Ghannouchi, le weekend dernier. Le lendemain d\u2019une interminable s\u00e9ance pl\u00e9ni\u00e8re \u00e0 l\u2019Assembl\u00e9e? Au moment o\u00f9 cinq de ses membres devenus ministres et secr\u00e9taires d\u2019Etat, membres du gouvernement Youssef Chahhed, devaient pr\u00eater serment \u00e0 Carthage? Un jour de fin de semaine? Par cette canicule?<\/p>\n<p style=\"text-align: left;\">La version donn\u00e9e par les m\u00e9dias \u2013 qui sacrifiait, une fois de plus, \u00e0 la sempiternelle langue de bois \u2013 \u00e9voquant une simple prise de contact avec les cadres et militants du parti islamiste, ne serions-nous pas en droit de fouiner un peu plus avant? C\u2019est, en fait, l\u2019aspect urgentissime rev\u00eatu par cette \u00abvisite de travail\u00bb qui nous a sembl\u00e9 plut\u00f4t singulier.<\/p>\n<p style=\"text-align: left;\"><em>Sc\u00e8ne 2<\/em> : La cha\u00eene t\u00e9l\u00e9vis\u00e9e nationale, la fameuse Canal 7 devenue Wataniya 1, a parachut\u00e9 dans le vingt heures du 27 ao\u00fbt 2016 un VTR de 4 minutes sur la baisse de la production du phosphate dans le bassin minier, en insistant sur l\u2019impact n\u00e9gatif de cette baisse en termes de pertes pour la \u00ab<em>collectivit\u00e9 nationale<\/em>\u00bb (sic). Une suite de donn\u00e9es brutes ass\u00e9n\u00e9es comme autant d\u2019arguments d\u2019autorit\u00e9, sans aucune analyse des tenants et aboutissants sociopolitiques de la crise mini\u00e8re, ni d\u00e9bat contradictoire. En un mot, la Tap d\u2019antan, revenant en grande pompe propagandiste.<\/p>\n<p style=\"text-align: left;\"><em>Sc\u00e8ne 3<\/em> : Lors du d\u00e9bat pr\u00e9c\u00e9dant le vote de confiance au gouvernement Chahed, un \u00ab<em>repr\u00e9sentant du peuple<\/em>\u00bb, principal acteur dans la crise mini\u00e8re, Adnane Hajji en l\u2019occurrence, a maugr\u00e9\u00e9 une mise en garde, trop v\u00e9h\u00e9mente pour \u00eatre purement sp\u00e9culative, \u00e0 l\u2019adresse du chef du gouvernement si celui-ci en venait \u00e0 des vell\u00e9it\u00e9s muscl\u00e9es en r\u00e9ponse \u00e0 l\u2019aporie du bassin minier. L\u00e0 aussi, le propos r\u00e9v\u00e9lait plus de non-dits qu\u2019il n\u2019exprimait une prise de position politique.<\/p>\n<p style=\"text-align: left;\"><em>Sc\u00e8ne 4<\/em> : Apr\u00e8s avoir fait allusion, dans son pr\u00e9ambule, \u00e0 la crise du phosphate, le chef du gouvernement, bottant en touche, a soigneusement \u00e9vit\u00e9 de revenir sur ce dossier, dans sa maladroite tentative d\u2019apaiser les craintes de certains d\u00e9put\u00e9s se rapportant aux \u00ab<em>mesures douloureuses<\/em>\u00bb que son gouvernement aurait \u00e0 prendre. Son pr\u00e9d\u00e9cesseur \u2013 faut-il le rappeler? \u2013 avait clairement affirm\u00e9, sous la m\u00eame coupole, que n\u2019ayant pas donn\u00e9 une suite favorable \u00e0 \u00ab<em>certaines pressions<\/em>\u00bb lui enjoignant d\u2019user de coercition dans la r\u00e9solution du dossier minier, son fauteuil minist\u00e9riel en devenait d\u2019autant plus \u00e9jectable.<\/p>\n<p style=\"text-align: left;\"><em>Sc\u00e8ne 5<\/em> : L\u2019empressement de l\u2019UGTT \u00e0 publier un communiqu\u00e9 tout en demi-teintes, \u00e9vasif \u00e0 souhait, o\u00f9 elle retirait visiblement son \u00e9pingle du jeu au cas o\u00f9\u2026 \u00ab<em>o\u00f9<\/em>\u00bb quoi pr\u00e9cis\u00e9ment? Les \u00ab<em>mesures douloureuses<\/em>\u00bb pr\u00e9conis\u00e9es par le FMI ne pouvant \u00eatre mises en place qu\u2019apr\u00e8s plusieurs semaines, voire plusieurs mois. Or, l\u00e0 encore, il semblerait qu\u2019il y ait urgence.<\/p>\n<p style=\"text-align: left;\"><em>Master scene<\/em> : Toutes ces donn\u00e9es conjugu\u00e9es nous am\u00e8nent \u00e0 une in\u00e9luctable conclusion. Le gouvernorat de Gafsa, conna\u00eetra, dans les prochains jours, et en rapport avec l\u2019\u00e9pineux dossier du bassin minier, de f\u00e2cheux \u00e9v\u00e9nements. Tel sera, \u00e0 mon sens, la premi\u00e8re des \u00abmesures douloureuses\u00bb annonc\u00e9es par le chef du gouvernement.<\/p>\n<p style=\"text-align: left;\"><strong>Les vieilles recettes \u00abnovembristes\u00bb<\/strong><\/p>\n<p style=\"text-align: left;\">A cet effet, certaines \u00e2mes charitables de la r\u00e9gion de Gafsa ont \u00e9t\u00e9 rappel\u00e9es \u00e0 leur devoir religieux. En bons musulmans, ils ont \u00e9t\u00e9 \u00ab<em>conseill\u00e9s<\/em>\u00bb, et c\u2019est en bons musulmans qu\u2019ils pr\u00eacheront \u00ab<em>la bonne parole<\/em>\u00bb aupr\u00e8s des brebis \u00e9gar\u00e9es. Les m\u00e9dias, pour leur part, ne seront pas en reste. La participation active de certaines plumes, voix et figures r\u00e9put\u00e9es pour leur probit\u00e9, ne manqueront pas au devoir national de sensibiliser \u00ab<em>le bon peuple tunisien<\/em>\u00bb \u00e0 la n\u00e9cessit\u00e9 de trouver une issue, m\u00eame au moyen d\u2019un traitement muscl\u00e9 de ce dossier, tant il est vrai qu\u2019il y va de la survie de l\u2019Etat tunisien.<\/p>\n<p style=\"text-align: left;\">La direction de l\u2019UGTT, elle, navigant, comme \u00e0 l\u2019accoutum\u00e9e, \u00e0 vue. Nullement opportuniste, elle fera passer le t\u00e9moin de vert qu\u2019il est \u00e0 l\u2019oranger, \u00e9vitant soigneusement le rouge, selon l\u2019\u00e9volution des \u00e9v\u00e9nements. C\u2019est, du moins, de la sorte que nous avons interpr\u00e9t\u00e9 son soutien critique au gouvernement Chahed.<\/p>\n<p style=\"text-align: left;\">Le facteur temps \u00e9tant, en l\u2019occurrence, d\u2019importance: tant qu\u2019\u00e0 faire, autant que le sale boulot soit assum\u00e9 par l\u2019actuelle \u00e9quipe aux commandes de la centrale syndicale. La nouvelle, quant \u00e0 elle, se contentera de <em>\u00abregretter\u00bb<\/em>, \u00e0 demi-mots, pareilles <em>\u00abmauvaises \u00e9valuations de la situation\u00bb<\/em>.<\/p>\n<p style=\"text-align: left;\">Tout ce beau monde semble oublier que ces contr\u00e9es \u00ab<em>lointaines<\/em>\u00bb \u00e9tant \u00e9reint\u00e9es \u00e0 force de brimades, les <em>\u00abautochtones\u00bb<\/em> sont, de ce fait, l\u00e9gitimement fond\u00e9s \u00e0 revendiquer de v\u00e9ritables alternatives \u00e0 leur mal-vie. Les exp\u00e9riences accumul\u00e9es au fil des ann\u00e9es ont prouv\u00e9 que les vieilles recettes <em>\u00abnovembristes\u00bb<\/em> (allusion au 7 novembre 1987, date d\u2019accession de Ben Ali au pouvoir, Ndlr), concoct\u00e9es \u00e0 coup de colmatage de br\u00e8ches, n\u2019ont eu, en la mati\u00e8re, qu\u2019un d\u00e9vastateur effet dominos pour notre pays.<\/p>\n<p style=\"text-align: left;\"><em>* Universitaire.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau chef du gouvernement Youssef Chahed usera-t-il de coercition pour faire red\u00e9marrer la machine de production de phosphate \u00e0 Gafsa ? Par Ass\u00e2ad Jom\u00e2a *<\/p>\n","protected":false},"author":8,"featured_media":62980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[992,1000,2433],"tags":[11521,133,407,418,711],"class_list":["post-62979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-tribune","category-tunisie","tag-adnane-hajji","tag-bassin-minier","tag-gafsa","tag-gouvernement","tag-phosphate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis\" \/>\n<meta property=\"og:description\" content=\"Le nouveau chef du gouvernement Youssef Chahed usera-t-il de coercition pour faire red\u00e9marrer la machine de production de phosphate \u00e0 Gafsa ? Par Ass\u00e2ad Jom\u00e2a *\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\" \/>\n<meta property=\"og:site_name\" content=\"Kapitalis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KapitalisInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-29T10:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/kapitalis-logo-fb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"webmaster kapitalis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:site\" content=\"@KapitalisInfo\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster kapitalis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\"},\"author\":{\"name\":\"webmaster kapitalis\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\"},\"headline\":\"\u00abMesures douloureuses\u00bb &#8211; Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa\",\"datePublished\":\"2016-08-29T10:20:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\"},\"wordCount\":1120,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Adnane Hajji\",\"bassin minier\",\"Gafsa\",\"gouvernement\",\"phosphate\"],\"articleSection\":[\"A LA UNE\",\"TRIBUNE\",\"Tunisie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\",\"name\":\"\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis\",\"isPartOf\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-08-29T10:20:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/kapitalis.com\/tunisie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMesures douloureuses\u00bb &#8211; Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#website\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"name\":\"Kapitalis\",\"description\":\"L&#039;actualit\u00e9 en Tunisie et dans le monde\",\"publisher\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#organization\",\"name\":\"Kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"contentUrl\":\"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png\",\"width\":5000,\"height\":1500,\"caption\":\"Kapitalis\"},\"image\":{\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/KapitalisInfo\/\",\"https:\/\/x.com\/KapitalisInfo\",\"https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9\",\"name\":\"webmaster kapitalis\",\"url\":\"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis","og_description":"Le nouveau chef du gouvernement Youssef Chahed usera-t-il de coercition pour faire red\u00e9marrer la machine de production de phosphate \u00e0 Gafsa ? Par Ass\u00e2ad Jom\u00e2a *","og_url":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/","og_site_name":"Kapitalis","article_publisher":"https:\/\/www.facebook.com\/KapitalisInfo\/","article_published_time":"2016-08-29T10:20:40+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/kapitalis-logo-fb.png","type":"image\/png"}],"author":"webmaster kapitalis","twitter_card":"summary_large_image","twitter_creator":"@KapitalisInfo","twitter_site":"@KapitalisInfo","twitter_misc":{"\u00c9crit par":"webmaster kapitalis","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#article","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/"},"author":{"name":"webmaster kapitalis","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9"},"headline":"\u00abMesures douloureuses\u00bb &#8211; Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa","datePublished":"2016-08-29T10:20:40+00:00","mainEntityOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/"},"wordCount":1120,"commentCount":3,"publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage"},"thumbnailUrl":"","keywords":["Adnane Hajji","bassin minier","Gafsa","gouvernement","phosphate"],"articleSection":["A LA UNE","TRIBUNE","Tunisie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/","url":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/","name":"\u00abMesures douloureuses\u00bb - Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa - Kapitalis","isPartOf":{"@id":"https:\/\/kapitalis.com\/tunisie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-08-29T10:20:40+00:00","breadcrumb":{"@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/kapitalis.com\/tunisie\/2016\/08\/29\/mesures-douloureuses-acte-1-pacification-du-bassin-minier-de-gafsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kapitalis.com\/tunisie\/"},{"@type":"ListItem","position":2,"name":"\u00abMesures douloureuses\u00bb &#8211; Acte 1 : \u00abPacification\u00bb du bassin minier de Gafsa"}]},{"@type":"WebSite","@id":"https:\/\/kapitalis.com\/tunisie\/#website","url":"https:\/\/kapitalis.com\/tunisie\/","name":"Kapitalis","description":"L&#039;actualit\u00e9 en Tunisie et dans le monde","publisher":{"@id":"https:\/\/kapitalis.com\/tunisie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kapitalis.com\/tunisie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kapitalis.com\/tunisie\/#organization","name":"Kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/","url":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","contentUrl":"https:\/\/kapitalis.com\/tunisie\/wp-content\/uploads\/2022\/05\/Kapitalis-big-size.png","width":5000,"height":1500,"caption":"Kapitalis"},"image":{"@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KapitalisInfo\/","https:\/\/x.com\/KapitalisInfo","https:\/\/www.youtube.com\/channel\/UC-yDYrHyfFBWWZaOw3FPg9Q"]},{"@type":"Person","@id":"https:\/\/kapitalis.com\/tunisie\/#\/schema\/person\/d71f33a9ca44f7bad4698210b480c8e9","name":"webmaster kapitalis","url":"https:\/\/kapitalis.com\/tunisie\/author\/webmaster-kapitalis\/"}]}},"_links":{"self":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/62979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/comments?post=62979"}],"version-history":[{"count":0,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/posts\/62979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media\/62980"}],"wp:attachment":[{"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/media?parent=62979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/categories?post=62979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kapitalis.com\/tunisie\/wp-json\/wp\/v2\/tags?post=62979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}